{"id":912,"date":"2025-09-03T19:35:52","date_gmt":"2025-09-03T19:35:52","guid":{"rendered":"https:\/\/meditrade.net\/?page_id=912"},"modified":"2026-05-18T12:37:52","modified_gmt":"2026-05-18T12:37:52","slug":"uber-uns","status":"publish","type":"page","link":"https:\/\/ch.meditrade.net\/de\/uber-uns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"912\" class=\"elementor elementor-912\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77749d1 vertical-padding side-padding section-height e-flex e-con-boxed e-con e-parent\" data-id=\"77749d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4c666b e-con-full Hero-Second-Layout-Design-Content e-flex e-con e-child\" data-id=\"c4c666b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7a87f Hero-Second-Layout-Design-Content-Title Font-Size-70 elementor-widget elementor-widget-heading\" data-id=\"4f7a87f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-401c3d9 elementor-widget elementor-widget-text-editor\" data-id=\"401c3d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Werden Sie Teil unseres engagierten Teams und gestalten Sie Ihre berufliche Zukunft mit uns.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e2675d elementor-align-left open-popup elementor-widget elementor-widget-button\" data-id=\"7e2675d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebot anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28320bf vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"28320bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8e12305 e-con-full content-container-style e-flex e-con e-child\" data-id=\"8e12305\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8bb4db elementor-widget elementor-widget-image\" data-id=\"f8bb4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1021\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM-1024x1021.png\" class=\"attachment-large size-large wp-image-9952\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM-1024x1021.png 1024w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM-300x300.png 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM-150x150.png 150w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM-768x765.png 768w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/About-us-Meditrade-10-17-2025_02_49_AM.png 1214w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e0cd2 e-con-full home-first-section-right e-flex e-con e-child\" data-id=\"65e0cd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb534a2 elementor-widget elementor-widget-heading\" data-id=\"bb534a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Leidenschaft f\u00fcr Gesundheit\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a703bb2 elementor-widget elementor-widget-heading\" data-id=\"a703bb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f94993 elementor-widget elementor-widget-text-editor\" data-id=\"4f94993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade ist eine international t\u00e4tige Unternehmensgruppe mit Sitz in Europa, die die Werte eines familiengef\u00fchrten Unternehmens mit umfassenden L\u00f6sungen f\u00fcr das Gesundheitswesen unter dem Leitgedanken<em>Leidenschaft f\u00fcr Gesundheit<\/em>\u00a0verbindet.<\/p><p>Mit einer Geschichte, die bis ins Jahr 1988 zur\u00fcckreicht, begann unsere Entwicklung als Hersteller medizinischer Einwegprodukte wie Handschuhe, Hauben und Masken. Seitdem hat sich Meditrade zu einem f\u00fchrenden Unternehmen auf dem europ\u00e4ischen Markt entwickelt und bietet heute ein Produktsortiment mit \u00fcber 1.500 Artikeln. Dieses umfasst unter anderem Handschuhe, Schutzbekleidung, Wundversorgung, Sets und chirurgisches Zubeh\u00f6r, Inkontinenzprodukte, Desinfektions- und Pflegeprodukte, Hygiene- und Reinigungsprodukte sowie Praxis- und Patientenbedarf.<\/p><p>Heute nutzen wir \u00fcber 38 Jahre Branchenerfahrung in ganz Europa, um Fachkr\u00e4fte im Gesundheitswesen dabei zu unterst\u00fctzen, eine bestm\u00f6gliche Patientenversorgung sicherzustellen. Unser Engagement f\u00fcr\u00a0<strong>Produkt<\/strong>\u00a0Exzellenz, Industrie\u00a0<strong>Fachwissen<\/strong>, stromlinienf\u00f6rmig\u00a0<strong>Logistik<\/strong>, sowie au\u00dfergew\u00f6hnliche\u00a0<strong>Kundenbetreuung<\/strong>\u00a0zeichnet uns in der Gesundheitsbranche aus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ba9f1c e-con-full e-flex e-con e-child\" data-id=\"8ba9f1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca09231 elementor-widget elementor-widget-heading\" data-id=\"ca09231\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Die Mission von Meditrade ist es, Fachkr\u00e4fte im Gesundheitswesen dabei zu unterst\u00fctzen, jeden Tag eine bestm\u00f6gliche Patientenversorgung zu gew\u00e4hrleisten.\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23b0c7b vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"23b0c7b\" data-element_type=\"container\" data-e-type=\"container\" id=\"about-product\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8498e0b e-con-full e-flex e-con e-child\" data-id=\"8498e0b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-96906ee e-con-full banner-image-text e-flex e-con e-child\" data-id=\"96906ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88da8b3 elementor-widget elementor-widget-heading\" data-id=\"88da8b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Leidenschaft f\u00fcr Gesundheit<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b887e74 elementor-widget elementor-widget-heading\" data-id=\"b887e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produktsortiment<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1db3dc elementor-widget elementor-widget-text-editor\" data-id=\"d1db3dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade bietet ein vielf\u00e4ltiges Sortiment hochwertiger Medizin- und Hygieneprodukte.<br \/>und bietet Fachkr\u00e4ften im Gesundheitswesen ma\u00dfgeschneiderte L\u00f6sungen<br \/>um eine erstklassige Patientenversorgung sicherzustellen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8204d76 e-con-full e-flex e-con e-child\" data-id=\"8204d76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-acd90b2 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"acd90b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b18c1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e3b18c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c2b2c6 elementor-widget elementor-widget-text-editor\" data-id=\"1c2b2c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>38 Jahre Erfahrung im internationalen Gesundheitsmarkt als Hersteller von mehr als 1.500 Produkten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8771d9 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"d8771d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6e16c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3e6e16c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b27e04 elementor-widget elementor-widget-text-editor\" data-id=\"3b27e04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Kontrolle s\u00e4mtlicher Stufen unserer Lieferkette erm\u00f6glicht es uns, h\u00f6chste Qualit\u00e4tsstandards zu gew\u00e4hrleisten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86d9566 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"86d9566\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14d8bdb elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"14d8bdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff187e elementor-widget elementor-widget-text-editor\" data-id=\"6ff187e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir entwickeln ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr individuelle Anforderungen gest\u00fctzt auf unsere Erfahrung aus dem Betrieb eigener Gesundheitseinrichtungen innerhalb unserer Unternehmensgruppe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7659157 vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"7659157\" data-element_type=\"container\" data-e-type=\"container\" id=\"about-expertise\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0801ba1 image-style elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0801ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-15.webp\" class=\"attachment-large size-large wp-image-1309\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-15.webp 1000w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-15-300x210.webp 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-15-768x538.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fad4289 e-con-full home-first-section-right e-flex e-con e-child\" data-id=\"fad4289\" data-element_type=\"container\" data-e-type=\"container\" id=\"flex-basis-style\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07d7e9e elementor-widget elementor-widget-heading\" data-id=\"07d7e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Expertise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5d6da6 elementor-widget elementor-widget-text-editor\" data-id=\"d5d6da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Neben der Versorgung des Gesundheitswesens mit essenziellen Verbrauchsmaterialien unterst\u00fctzt Meditrade seine Kunden auch mit Beratungs- und Serviceleistungen bei regulatorischen Anforderungen, branchenspezifischen Vorgaben sowie fundierten Entscheidungsprozessen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da3b7aa e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"da3b7aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b31695 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2b31695\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed7a2e3 elementor-widget elementor-widget-text-editor\" data-id=\"ed7a2e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>BRANCHENVERST\u00c4NDNIS: Fr\u00fchzeitiges Erkennen neuer Anforderungen und konsequente Ausrichtung an den Entwicklungen der Branche<br \/>durch ein tiefgehendes Verst\u00e4ndnis des Gesundheitssektors.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b638374 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"b638374\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e223995 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e223995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cba72 elementor-widget elementor-widget-text-editor\" data-id=\"c6cba72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>REGULATORISCHE KOMPETENZ: Sicherstellung der Einhaltung geltender Richtlinien und verl\u00e4ssliche Unterst\u00fctzung<br \/>durch fundiertes Wissen \u00fcber nationale und internationale<br \/>regulatorische Anforderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7e7f21 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"f7e7f21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8587c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fd8587c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-766098f elementor-widget elementor-widget-text-editor\" data-id=\"766098f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Strategische Beratung und wertvolle Branchenkenntnisse auf Basis langj\u00e4hriger Erfahrung<br \/>des Meditrade-Teams.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-054ba23 vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"054ba23\" data-element_type=\"container\" data-e-type=\"container\" id=\"about-logistics\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c1b2aa3 e-con-full home-first-section-right e-flex e-con e-child\" data-id=\"c1b2aa3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-655a58f elementor-widget elementor-widget-heading\" data-id=\"655a58f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Logistik\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19bb5b2 elementor-widget elementor-widget-text-editor\" data-id=\"19bb5b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade gew\u00e4hrleistet einen reibungslosen Warenfluss durch optimierte regionale Distribution, kurze Lieferzeiten und effiziente Zollabwicklungen innerhalb der Europ\u00e4ischen Union, der Schweiz und des Vereinigten K\u00f6nigreichs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4294b5 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"a4294b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa954e2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"aa954e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd64818 elementor-widget elementor-widget-text-editor\" data-id=\"cd64818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>EFFIZIENTE DISTRIBUTION: Minimierung von Lieferzeiten und Kosten durch strategisch positionierte Lagerstandorte in der EU und im Vereinigten K\u00f6nigreich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-943677e e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"943677e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dde4270 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dde4270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0579ca9 elementor-widget elementor-widget-text-editor\" data-id=\"0579ca9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>LOKALES BESTANDSMANAGEMENT: Schnelle Reaktion auf Kundenanforderungen und spezifische Marktbed\u00fcrfnisse zur Reduzierung von Lieferzeiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc3b4c2 e-con-full srf-third-section-content e-flex e-con e-child\" data-id=\"cc3b4c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9cfb06 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f9cfb06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewbox=\"0 0 24 24\" fill=\"none\" transform=\"rotate(0 0 0)\"><path d=\"M2 12C2 6.47715 6.47715 2 12 2C17.5228 2 22 6.47715 22 12C22 17.5228 17.5228 22 12 22C6.47715 22 2 17.5228 2 12Z\" fill=\"#343C54\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f72c2 elementor-widget elementor-widget-text-editor\" data-id=\"25f72c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>LAGERKAPAZIT\u00c4TEN: Unsere umfangreichen Lagerkapazit\u00e4ten erm\u00f6glichen es uns, gro\u00dfe Warenmengen vorzuhalten und eine durchg\u00e4ngige Produktverf\u00fcgbarkeit zu gew\u00e4hrleisten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c2993 image-style elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b7c2993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-16.webp\" class=\"attachment-large size-large wp-image-1313\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-16.webp 800w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-16-300x225.webp 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-16-768x576.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f99a6d8 vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"f99a6d8\" data-element_type=\"container\" data-e-type=\"container\" id=\"about-service\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b212258 e-con-full home-first-section-right e-flex e-con e-child\" data-id=\"b212258\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c212a elementor-widget elementor-widget-heading\" data-id=\"b5c212a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Schnelle Unterst\u00fctzung\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c57422 elementor-widget elementor-widget-heading\" data-id=\"8c57422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dienstleistungen\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b7d0bb elementor-widget elementor-widget-text-editor\" data-id=\"2b7d0bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade legt gro\u00dfen Wert auf langfristige Kundenbeziehungen und bietet pers\u00f6nliche sowie zuverl\u00e4ssige Betreuung. Durch kontinuierlichen Austausch, aktives Einholen von Feedback und den Anspruch, Erwartungen zu \u00fcbertreffen, unterst\u00fctzen wir den nachhaltigen Erfolg unserer Kunden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-553c0f0 e-con-full e-grid e-con e-child\" data-id=\"553c0f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ff8d4e7 e-con-full e-flex e-con e-child\" data-id=\"ff8d4e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69c6897 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"69c6897\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/component-358.svg\" class=\"attachment-large size-large wp-image-2598\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b08aaa4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b08aaa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Schnelle Unterst\u00fctzung\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1589732 elementor-widget elementor-widget-text-editor\" data-id=\"1589732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Zeitnahe Bearbeitung von Anfragen, Anliegen und Herausforderungen durch unser jederzeit erreichbares Kundenservice-Team.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9a7821 e-con-full e-flex e-con e-child\" data-id=\"d9a7821\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc06847 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"bc06847\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/component-358-1.svg\" class=\"attachment-large size-large wp-image-2595\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a4a04 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"42a4a04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Individuelle Betreuung\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f83bfbf elementor-widget elementor-widget-text-editor\" data-id=\"f83bfbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr spezifische Kundenanforderungen und der Aufbau langfristiger, vertrauensvoller Partnerschaften.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ece9484 e-con-full e-flex e-con e-child\" data-id=\"ece9484\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a6fcf6 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"0a6fcf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/component-358-2.svg\" class=\"attachment-large size-large wp-image-2596\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e3b57d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0e3b57d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">EFFIZIENTE AUFTRAGSABWICKLUNG\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f68df42 elementor-widget elementor-widget-text-editor\" data-id=\"f68df42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dank unserer effizienten und optimierten Prozesse erm\u00f6glichen wir eine schnelle, pr\u00e4zise Auftragsbearbeitung - auch am selben Tag.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ee2da0 e-con-full e-flex e-con e-child\" data-id=\"8ee2da0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff6897 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"6ff6897\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/component-358-3.svg\" class=\"attachment-large size-large wp-image-2597\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2c8000 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e2c8000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Kontinuierliche Weiterentwicklung\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b049bd elementor-widget elementor-widget-text-editor\" data-id=\"8b049bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Durch aktives Einholen von Feedback und die fortlaufende Optimierung unserer Prozesse verbessern wir kontinuierlich das Kundenerlebnis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6beb60 vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"f6beb60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f57171 elementor-widget__width-initial image-style elementor-widget elementor-widget-image\" data-id=\"6f57171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"491\" height=\"748\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-17.webp\" class=\"attachment-large size-large wp-image-1332\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-17.webp 491w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/09\/webpc-passthru-17-197x300.webp 197w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c0094f e-con-full home-first-section-right e-flex e-con e-child\" data-id=\"7c0094f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-423db19 elementor-widget elementor-widget-heading\" data-id=\"423db19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Logistikzentren\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd2867e elementor-widget elementor-widget-text-editor\" data-id=\"cd2867e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Durch strategisch positionierte Lagerstandorte in Deutschland und im Vereinigten K\u00f6nigreich gew\u00e4hrleistet Meditrade einen reibungslosen Warenfluss, optimierte regionale Distribution, kurze Lieferzeiten sowie effiziente Zollabwicklungen innerhalb der Europ\u00e4ischen Union, der Schweiz und des Vereinigten K\u00f6nigreichs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51c2e58 e-grid e-con-full e-con e-child\" data-id=\"51c2e58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-286c4ea e-con-full e-flex e-con e-child\" data-id=\"286c4ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ceadb56 e-con-full e-flex e-con e-child\" data-id=\"ceadb56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71fef92 logistic_number elementor-widget elementor-widget-heading\" data-id=\"71fef92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">4<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4f5a29 logistic_number_title elementor-widget elementor-widget-heading\" data-id=\"f4f5a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Standorte<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4545118 elementor-widget elementor-widget-heading\" data-id=\"4545118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">logistische Knotenpunkte in der EU und im Vereinigten K\u00f6nigreich\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1728304 e-con-full e-flex e-con e-child\" data-id=\"1728304\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b2ec79c e-con-full e-flex e-con e-child\" data-id=\"b2ec79c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2461a10 logistic_number elementor-widget elementor-widget-heading\" data-id=\"2461a10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">48<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec88fb logistic_number_title elementor-widget elementor-widget-heading\" data-id=\"4ec88fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">K<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c0e913 elementor-widget elementor-widget-heading\" data-id=\"1c0e913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Paletten kombinierte Lagerkapazit\u00e4t\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bde5dad e-con-full e-flex e-con e-child\" data-id=\"bde5dad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1825137 e-con-full e-flex e-con e-child\" data-id=\"1825137\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-860a504 logistic_number elementor-widget elementor-widget-heading\" data-id=\"860a504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">99<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-786245c logistic_number_title elementor-widget elementor-widget-heading\" data-id=\"786245c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">%\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-303795f elementor-widget elementor-widget-heading\" data-id=\"303795f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Lagerverf\u00fcgbarkeit\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1cfaae e-con-full e-flex e-con e-child\" data-id=\"f1cfaae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7052d56 e-con-full e-flex e-con e-child\" data-id=\"7052d56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af7e0c5 logistic_number elementor-widget elementor-widget-heading\" data-id=\"af7e0c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">24<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e27a2e7 logistic_number_title elementor-widget elementor-widget-heading\" data-id=\"e27a2e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">h\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c20e030 elementor-widget elementor-widget-heading\" data-id=\"c20e030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Maximale Auftragsbearbeitungszeit\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b72adfb vertical-padding side-padding e-flex e-con-boxed e-con e-parent\" data-id=\"b72adfb\" data-element_type=\"container\" data-e-type=\"container\" id=\"about-history\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-105da6a elementor-widget elementor-widget-heading\" data-id=\"105da6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meilensteine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbf905 elementor-widget elementor-widget-heading\" data-id=\"ffbf905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geschichte\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8930f49 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8930f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Geschichte der Meditrade Group begann 1988 mit der Gr\u00fcndung der Meditrade GmbH durch Peter R\u00f6sner-Mautby. Was zun\u00e4chst als Hersteller von Handschuhen startete, entwickelte sich zu einem der f\u00fchrenden Anbieter medizinischer Produkte in Europa.\nAuch in Zukunft bleibt die Meditrade Group ihrer Mission treu: Fachkr\u00e4ften im Gesundheitswesen Zugang zu einem stetig wachsenden Sortiment innovativer Produkte und L\u00f6sungen zu bieten. Gemeinsam gestalten wir die Zukunft des Gesundheitswesens und schaffen die Grundlage f\u00fcr eine ges\u00fcndere Zukunft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31061bd e-n-tabs-none elementor-widget elementor-widget-n-tabs\" data-id=\"31061bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;center&quot;,&quot;horizontal_scroll&quot;:&quot;enable&quot;,&quot;tabs_justify_horizontal_mobile&quot;:&quot;center&quot;,&quot;horizontal_scroll_mobile&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"51405245\" aria-label=\"Registerkarten. \u00d6ffnen Sie Elemente mit Enter oder Space, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t\t<button id=\"e-n-tab-title-514052451\" data-tab-title-id=\"e-n-tab-title-514052451\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-514052451\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t1988\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052452\" data-tab-title-id=\"e-n-tab-title-514052452\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052452\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tVor 1990\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052453\" data-tab-title-id=\"e-n-tab-title-514052453\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052453\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t1990\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052454\" data-tab-title-id=\"e-n-tab-title-514052454\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052454\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2010\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052455\" data-tab-title-id=\"e-n-tab-title-514052455\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052455\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2012\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052456\" data-tab-title-id=\"e-n-tab-title-514052456\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052456\" style=\"--n-tabs-title-order: 6;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2016\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052457\" data-tab-title-id=\"e-n-tab-title-514052457\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052457\" style=\"--n-tabs-title-order: 7;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2018\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-514052458\" data-tab-title-id=\"e-n-tab-title-514052458\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-514052458\" style=\"--n-tabs-title-order: 8;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2020\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-514052451\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052451\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-2c4f0ec e-con-full e-flex e-con e-child\" data-id=\"2c4f0ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-29eab46 e-grid e-con-boxed e-con e-child\" data-id=\"29eab46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1bb8b63 e-con-full e-flex e-con e-child\" data-id=\"1bb8b63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-77ac728 e-con-full e-flex e-con e-child\" data-id=\"77ac728\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c72c335 logistic_number elementor-widget elementor-widget-heading\" data-id=\"c72c335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">19<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9309cd logistic_number elementor-widget elementor-widget-heading\" data-id=\"d9309cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">88<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b598e elementor-widget elementor-widget-text-editor\" data-id=\"68b598e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Gr\u00fcndung des Unternehmens als Hersteller medizinischer Einwegprodukte wie Handschuhe, Hauben, Masken und Desinfektionsprodukte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dbf2b7 e-con-full e-flex e-con e-child\" data-id=\"0dbf2b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7faf7 elementor-widget elementor-widget-image\" data-id=\"dd7faf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"453\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-1024x453.jpg\" class=\"attachment-large size-large wp-image-9959\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-1024x453.jpg 1024w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-300x133.jpg 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-768x340.jpg 768w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-1536x680.jpg 1536w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/dsc02811-e1691416069155-2048x906.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052452\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052452\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-006897a e-con-full e-flex e-con e-child\" data-id=\"006897a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05f1c7b e-grid e-con-boxed e-con e-child\" data-id=\"05f1c7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b3a8376 e-con-full e-flex e-con e-child\" data-id=\"b3a8376\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b120ae0 e-con-full e-flex e-con e-child\" data-id=\"b120ae0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84942f0 logistic_number elementor-widget elementor-widget-heading\" data-id=\"84942f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">vor <br>\n1990<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-673352a elementor-widget elementor-widget-text-editor\" data-id=\"673352a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erweiterung des Unternehmens durch den Erwerb und die Beteiligung an mehreren Produktionsunternehmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-baca00b e-con-full e-flex e-con e-child\" data-id=\"baca00b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd40499 elementor-widget elementor-widget-image\" data-id=\"bd40499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"404\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-1024x404.webp\" class=\"attachment-large size-large wp-image-9964\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-1024x404.webp 1024w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-300x118.webp 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-768x303.webp 768w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-1536x605.webp 1536w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-6-2048x807.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052453\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052453\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-7195401 e-con-full e-flex e-con e-child\" data-id=\"7195401\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0f2f018 e-grid e-con-boxed e-con e-child\" data-id=\"0f2f018\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6b675c2 e-con-full e-flex e-con e-child\" data-id=\"6b675c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-71c66c2 e-con-full e-flex e-con e-child\" data-id=\"71c66c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5da4028 logistic_number elementor-widget elementor-widget-heading\" data-id=\"5da4028\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">19<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10bba47 logistic_number elementor-widget elementor-widget-heading\" data-id=\"10bba47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">90<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2214c8d elementor-widget elementor-widget-text-editor\" data-id=\"2214c8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade treibt seine internationale Expansion in Asien mit der \u00dcbernahme der ersten Handschuhfabriken voran. Durch diesen strategischen Schritt gewinnen wir mehr Kontrolle \u00fcber die Lieferkette und k\u00f6nnen unseren Kunden noch individuellere L\u00f6sungen bieten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c07069 e-con-full e-flex e-con e-child\" data-id=\"7c07069\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c83b2f2 elementor-widget elementor-widget-image\" data-id=\"c83b2f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"276\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-7.webp\" class=\"attachment-large size-large wp-image-9968\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-7.webp 700w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-7-300x118.webp 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052454\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052454\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\"elementor-element elementor-element-a0bbcc2 e-con-full e-flex e-con e-child\" data-id=\"a0bbcc2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5906c46 e-grid e-con-boxed e-con e-child\" data-id=\"5906c46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fcf3a00 e-con-full e-flex e-con e-child\" data-id=\"fcf3a00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b6b8ae2 e-con-full e-flex e-con e-child\" data-id=\"b6b8ae2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcfc3be logistic_number elementor-widget elementor-widget-heading\" data-id=\"bcfc3be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">20<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2663ee5 logistic_number elementor-widget elementor-widget-heading\" data-id=\"2663ee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">10<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e577b elementor-widget elementor-widget-text-editor\" data-id=\"43e577b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erweiterung des Produktportfolios um hochwertige Verbandstoffe und Inkontinenzprodukte durch die \u00dcbernahme des traditionsreichen, \u00fcber 90 Jahre alten Unternehmens Karl Beese GmbH &amp; Co. KG aus Hamburg mit eigenen Produktionsstandorten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f78da5 e-con-full e-flex e-con e-child\" data-id=\"4f78da5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-222c805 elementor-widget elementor-widget-image\" data-id=\"222c805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"404\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-1024x404.webp\" class=\"attachment-large size-large wp-image-9969\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-1024x404.webp 1024w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-300x118.webp 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-768x303.webp 768w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-1536x605.webp 1536w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-8-2048x807.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052455\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052455\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\"elementor-element elementor-element-3c2e4ca e-con-full e-flex e-con e-child\" data-id=\"3c2e4ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e487bdf e-grid e-con-boxed e-con e-child\" data-id=\"e487bdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ded8ba0 e-con-full e-flex e-con e-child\" data-id=\"ded8ba0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4907ece e-con-full e-flex e-con e-child\" data-id=\"4907ece\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b928f45 logistic_number elementor-widget elementor-widget-heading\" data-id=\"b928f45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">20<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06a341e logistic_number elementor-widget elementor-widget-heading\" data-id=\"06a341e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">12<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca7974 elementor-widget elementor-widget-text-editor\" data-id=\"1ca7974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Umzug in den neuen Unternehmensstandort in Kiefersfelden, Deutschland. Seitdem setzen wir unseren erfolgreichen Wachstumskurs in Kiefersfelden fort und haben uns zu einem f\u00fchrenden Unternehmen der Branche entwickelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57551e9 e-con-full e-flex e-con e-child\" data-id=\"57551e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b64bbbf elementor-widget elementor-widget-image\" data-id=\"b64bbbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"276\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-9.webp\" class=\"attachment-large size-large wp-image-9973\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-9.webp 700w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-9-300x118.webp 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052456\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052456\" data-tab-index=\"6\" style=\"--n-tabs-title-order: 6;\" class=\"elementor-element elementor-element-a5dec08 e-con-full e-flex e-con e-child\" data-id=\"a5dec08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-34dd4c4 e-grid e-con-boxed e-con e-child\" data-id=\"34dd4c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c22ed4a e-con-full e-flex e-con e-child\" data-id=\"c22ed4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4350bf6 e-con-full e-flex e-con e-child\" data-id=\"4350bf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8eb0e81 logistic_number elementor-widget elementor-widget-heading\" data-id=\"8eb0e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">2016<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a98fdac elementor-widget elementor-widget-text-editor\" data-id=\"a98fdac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcbernahme der Mehrheitsbeteiligung an der MaiMed Group.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65b0ea8 e-con-full e-flex e-con e-child\" data-id=\"65b0ea8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6509b95 elementor-widget elementor-widget-image\" data-id=\"6509b95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"276\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-10.webp\" class=\"attachment-large size-large wp-image-9974\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-10.webp 700w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-10-300x118.webp 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052457\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052457\" data-tab-index=\"7\" style=\"--n-tabs-title-order: 7;\" class=\"elementor-element elementor-element-708ca4e e-con-full e-flex e-con e-child\" data-id=\"708ca4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4dcd40b e-grid e-con-boxed e-con e-child\" data-id=\"4dcd40b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e384a8 e-con-full e-flex e-con e-child\" data-id=\"7e384a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c27289e e-con-full e-flex e-con e-child\" data-id=\"c27289e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5523a1 logistic_number elementor-widget elementor-widget-heading\" data-id=\"b5523a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">20<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcf4a15 logistic_number elementor-widget elementor-widget-heading\" data-id=\"dcf4a15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">18<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae959d8 elementor-widget elementor-widget-text-editor\" data-id=\"ae959d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erweiterung des Logistikzentrums in Neuenkirchen, Deutschland, anl\u00e4sslich des 30-j\u00e4hrigen Bestehens von Meditrade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ccc1df e-con-full e-flex e-con e-child\" data-id=\"8ccc1df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d30167e elementor-widget elementor-widget-image\" data-id=\"d30167e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"403\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11-1024x403.webp\" class=\"attachment-large size-large wp-image-9975\" alt=\"\" srcset=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11-1024x403.webp 1024w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11-300x118.webp 300w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11-768x302.webp 768w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11-1536x605.webp 1536w, https:\/\/ch.meditrade.net\/wp-content\/uploads\/2025\/10\/webpc-passthru-11.webp 1824w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-514052458\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-514052458\" data-tab-index=\"8\" style=\"--n-tabs-title-order: 8;\" class=\"elementor-element elementor-element-27e864f e-con-full e-flex e-con e-child\" data-id=\"27e864f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a49e9b e-grid e-con-boxed e-con e-child\" data-id=\"2a49e9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-41de329 e-con-full e-flex e-con e-child\" data-id=\"41de329\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-147cbef e-con-full e-flex e-con e-child\" data-id=\"147cbef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-087c74b logistic_number elementor-widget elementor-widget-heading\" data-id=\"087c74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">2020<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ef595 elementor-widget elementor-widget-text-editor\" data-id=\"b2ef595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meditrade hat seine internationale Expansion mit der Gr\u00fcndung von Meditrade UK, einer Tochtergesellschaft mit Sitz in London, weiter vorangetrieben. Dadurch sind wir unseren Kunden im Vereinigten K\u00f6nigreich und in Irland noch n\u00e4her gekommen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b57b46 e-con-full e-flex e-con e-child\" data-id=\"8b57b46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>About us Join our Dedicated Team to build a Rewarding Career Request a quote Passion in Health About us Meditrade is a European-based global group of companies with the values of a family-run business offering comprehensive healthcare solutions under the #Passion in Health\u00a0maxim. With a legacy dating back to 1988, our journey began as a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-912","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/pages\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/comments?post=912"}],"version-history":[{"count":5,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/pages\/912\/revisions"}],"predecessor-version":[{"id":91210368,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/pages\/912\/revisions\/91210368"}],"wp:attachment":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/media?parent=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}