{"id":451,"date":"2023-03-30T15:18:58","date_gmt":"2023-03-30T12:18:58","guid":{"rendered":"https:\/\/meditrade.net\/?p=451"},"modified":"2025-10-16T21:40:52","modified_gmt":"2025-10-16T21:40:52","slug":"meditrade-nimmt-gemeinsam-mit-branchenfuhrern-am-prospitalia-jahreskongress-2023-teil","status":"publish","type":"post","link":"https:\/\/ch.meditrade.net\/de\/meditrade-nimmt-gemeinsam-mit-branchenfuhrern-am-prospitalia-jahreskongress-2023-teil\/","title":{"rendered":"Meditrade nimmt gemeinsam mit Branchenf\u00fchrern am Prospitalia-Jahreskongress 2023 teil"},"content":{"rendered":"<p>Mit der aktiven Teilnahme am Prospitalia-Jahreskongress, der am 27. und 28. M\u00e4rz in Frankfurt am Main stattfand, startete Meditrade in eine spannende Woche. Als f\u00fchrende deutsche Beschaffungsplattform f\u00fcr das Gesundheitswesen veranstaltete Prospitalia seinen ersten Jahreskongress vor Ort seit 2019 und brachte 40 prominente Anbieter aus dem Gesundheitswesen zusammen, darunter auch Meditrade.<\/p>\n<p>&nbsp;<\/p>\n<p>W\u00e4hrend des ereignisreichen Programms vor Ort hatte Meditrade das Privileg, mit Partnern aus der Industrie in Kontakt zu treten, neue Produkte vorzustellen, wertvolle Einblicke in die Branche zu geben und Diskussionen \u00fcber die gemeinsame Gestaltung der Zukunft des Gesundheitswesens anzuregen.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-3201\" src=\"https:\/\/ch.meditrade.net\/wp-content\/uploads\/2023\/04\/prospitalia-congress-linkedin-post-1200-\u00d7-1000px-360x300.png\" alt=\"\" width=\"360\" height=\"300\" \/><\/p>\n<p>Meditrade ist seit \u00fcber 30 Jahren auf dem dynamischen und sich st\u00e4ndig weiterentwickelnden Gesundheitsmarkt t\u00e4tig und setzt sich f\u00fcr kontinuierliche Verbesserungen und Innovationen ein. Wir wissen, wie wichtig es ist, die hohen Anforderungen und Erwartungen der Fachkr\u00e4fte im Gesundheitswesen zu erf\u00fcllen, und dieser Kongress war eine hervorragende Plattform f\u00fcr den Austausch von Ideen und Wissen, um die Branche voranzubringen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir m\u00f6chten unseren langj\u00e4hrigen Partnern der Prospitalia GmbH f\u00fcr die Organisation dieser bemerkenswerten Veranstaltung unseren aufrichtigen Dank aussprechen. Der Jahreskongress bot ein g\u00fcnstiges Umfeld, um sinnvolle Verbindungen zu f\u00f6rdern, Partnerschaften zu st\u00e4rken und den Gesundheitssektor gemeinsam voranzubringen.<\/p>","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend dieses Projekts testeten die Qualit\u00e4ts- und Aufsichtsbeh\u00f6rdenteams die Produktionsleistung in mehreren Phasen. Es war von entscheidender Bedeutung zu wissen, ob Medline das Produkt in \u00dcbereinstimmung mit den geforderten Standards durch die Versuchscharge der Kits liefern konnte. Die Ergebnisse der Testreihen fielen positiv aus, so dass der Projektauftakt<\/p>","protected":false},"author":2,"featured_media":9862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"template-pages\/template-news.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[63,64,65],"tags":[],"class_list":["post-451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news","category-company-news-germany","category-company-news-austria"],"acf":[],"_links":{"self":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/posts\/451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":1,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/posts\/451\/revisions"}],"predecessor-version":[{"id":9863,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/posts\/451\/revisions\/9863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/media\/9862"}],"wp:attachment":[{"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/media?parent=451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/categories?post=451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ch.meditrade.net\/de\/wp-json\/wp\/v2\/tags?post=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}